{"id":780,"date":"2022-01-12T07:00:46","date_gmt":"2022-01-12T07:00:46","guid":{"rendered":"https:\/\/auladeacordeon.com.br\/blog\/?p=780"},"modified":"2022-04-13T20:27:49","modified_gmt":"2022-04-13T20:27:49","slug":"a-importancia-cultural-da-sanfona-2","status":"publish","type":"post","link":"https:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/","title":{"rendered":"A import\u00e2ncia cultural da sanfona!"},"content":{"rendered":"<p>Com uma trajet\u00f3ria de mais de 3.000 anos ao redor do mundo, a sanfona encontrou em diversas culturas uma forma de expressas seus sons \u00fanicos e vers\u00e1teis. Pensando nisso, preparamos este artigo com a relev\u00e2ncia cultural predominantemente brasileira desse instrumento t\u00e3o amado em diversos ritmos musicais.<\/p>\n<h2>\u00c9 um instrumento popular no mundo?<\/h2>\n<p>Sim, apesar de ter no forr\u00f3 e na m\u00fasica nordestina suas grandes refer\u00eancias, encontramos suas melodias ao redor do mundo, principalmente na m\u00fasica folcl\u00f3rica de outros pa\u00edses.<\/p>\n<p>\u00c9 poss\u00edvel encontrar a sanfona tamb\u00e9m no fado, nos tangos e na valsa, al\u00e9m do mesmo instrumento fazer parte de orquestras sinf\u00f4nicas assinadas por grandes nomes da m\u00fasica erudita, como o italiano\u00a0<strong>Mirco Patarini<\/strong>\u00a0e o brasileiro\u00a0<strong>Hermeto Pascoal<\/strong>.<\/p>\n<p>Com a disponibilidade do encontro virtual, o\u00a0<strong>Festival Internacional de Sanfona de 2021<\/strong>\u00a0contou ainda com a apresenta\u00e7\u00e3o de instrumentistas argentinos e franceses provando a presen\u00e7a do instrumento at\u00e9 os dias atuais em outras culturas.<\/p>\n<figure id=\"attachment_666\" aria-describedby=\"caption-attachment-666\" style=\"width: 339px\" class=\"wp-caption alignleft\"><img class=\" wp-image-666\" src=\"http:\/\/auladeacordeon.com.br\/blog\/wp-content\/uploads\/2021\/10\/auladeacordeon.com_.br-blog-historia-1-2022-633x400.jpg\" alt=\"Como aprender acordeon\" width=\"339\" height=\"214\" srcset=\"https:\/\/auladeacordeon.com.br\/blog\/wp-content\/uploads\/2021\/10\/auladeacordeon.com_.br-blog-historia-1-2022-633x400.jpg 633w, https:\/\/auladeacordeon.com.br\/blog\/wp-content\/uploads\/2021\/10\/auladeacordeon.com_.br-blog-historia-1-2022.jpg 728w\" sizes=\"(max-width: 339px) 100vw, 339px\" \/><figcaption id=\"caption-attachment-666\" class=\"wp-caption-text\">Aprender a tocar acordeon tamb\u00e9m leva tempo e depende de etapas para ser finalizado<\/figcaption><\/figure>\n<h2>Como e quando o Brasil descobre o instrumento<\/h2>\n<p>Com a chegada de imigrantes europeus, especialmente italianos e alem\u00e3es que se instalaram no sul do pa\u00eds, a sanfona teve seu primeiro contato com o solo brasileiro. O primeiro instrumento trazido por eles era chamado de Concertina e era um Crom\u00e1tico de 120 bot\u00f5es.<\/p>\n<p>Popular no Sul do pa\u00eds, a sanfona chegou \u00e0 Regi\u00e3o Norte e Nordeste por soldados nordestinos que lutaram na guerra do Paraguai em 1864-70. Foi nesta regi\u00e3o que a sanfona recebeu este nome e passou a ser cada vez mais explorada trazendo novas carater\u00edsticas \u00fanicas na sua afina\u00e7\u00e3o e interpreta\u00e7\u00e3o.<\/p>\n<h2>A marcante presen\u00e7a da sanfona na cultura popular<\/h2>\n<p>Indispens\u00e1vel nas festas juninas, a sanfona faz parte do ritmo musical mais famosos no nordeste: o forr\u00f3. Da mesma forma sua melodia \u00e9 encontrada no musical regional ga\u00facha e nas noites frias com chimarr\u00e3o. E at\u00e9 mesmo se misturando com ritmos eletr\u00f4nicos nas festas pelo Brasil apresentando o chamado\u00a0<strong><em>tecnobrega<\/em><\/strong>\u00a0e at\u00e9 mesmo a\u00a0<strong><em>pisadinha<\/em><\/strong>.<\/p>\n<p>Foi com Gonzaga que a sanfona recebeu sua caracter\u00edstica predominante brasileira. Antes dele, o instrumento era utilizado predominante em tangos, na valsa ou na rancheira, ou seja, express\u00f5es musicais de origem estrangeira.<\/p>\n<p>Al\u00e9m disso, ele incentivou diversos sanfoneiros ao redor do Brasil a come\u00e7arem a cantar junto. Consagrando-se como um dos maiores nomes dentro dos ritmos da m\u00fasica popular brasileira.<\/p>\n<p>No nosso pen\u00faltimo\u00a0<a href=\"http:\/\/auladeacordeon.com.br\/blog\/a-historia-do-acordeon\/\" target=\"_blank\" rel=\"noopener\">artigo aqui no blog n\u00f3s trouxemos um pouco mais sobre a hist\u00f3ria<\/a>\u00a0do instrumento e seus estilos musicais. Confere l\u00e1!<\/p>\n<h2>Verdades e mentiras sobre a sanfona<\/h2>\n<p>Separamos aqui algumas verdades e mentiras sobre o instrumento mais amado desse blog, confira abaixo:<\/p>\n<h3><strong><u>Sanfona, gaita e acordeon s\u00e3o a mesma coisa! VERDADE<\/u><\/strong><\/h3>\n<p>Elas variam com de acordo com a regi\u00e3o do falante. Ent\u00e3o encontramos a sanfona no norte e no nordeste, a gaita no sul e o acordeon no sudeste. [inserir artigo 2 de outubro do blog como link]\n<h3><strong><u>A sanfona n\u00e3o possibilita a cria\u00e7\u00e3o de arranjos ricos! MENTIRA<\/u><\/strong><\/h3>\n<p>Justamente por ser t\u00e3o ligada a tradi\u00e7\u00f5es e por sua constru\u00e7\u00e3o completa, a sanfona \u00e9 vers\u00e1til e torna poss\u00edvel a cria\u00e7\u00e3o de arranjos ricos que funcionam em qualquer g\u00eanero ou estilo musical.<\/p>\n<h3><strong><u>Existem in\u00fameras varia\u00e7\u00f5es de tamanhos! VERDADE<\/u><\/strong><\/h3>\n<p>N\u00e3o s\u00f3 diversos tamanhos, como tamb\u00e9m baixos, teclas ou bot\u00f5es e afina\u00e7\u00f5es, por isso pesquise bastante e consulte algu\u00e9m de confian\u00e7a antes de comprar a sua.<\/p>\n<h3><strong><u>A sanfona chegou primeiro no centro-oeste! MENTIRA<\/u><\/strong><\/h3>\n<p>Na realidade, ela chegou em 1846 na cidade de S\u00e3o Leopoldo no Rio Grande do Sul, por imigrantes alem\u00e3es.<\/p>\n<h3><strong><u>Apenas com um dedo voc\u00ea consegue tocar muitas notas! VERDADE<\/u><\/strong><\/h3>\n<p>O que acontece \u00e9 que s\u00f3 com o bot\u00e3o dos baixos \u00e9 poss\u00edvel emitir acordes com tr\u00eas notas diferentes, combinando at\u00e9 cinco oitavas. S\u00f3 com um dedo voc\u00ea pode tocar v\u00e1rias notas e se encantar com as possibilidades musicais.<\/p>\n<h2>Que artistas tornam a sanfona t\u00e3o amada no Brasil<\/h2>\n<p>N\u00e3o poder\u00edamos deixar de fora alguns dos grandes sanfoneiros do nosso pa\u00eds, tanto daqueles que tornaram o instrumento t\u00e3o amado, quanto daqueles que o mant\u00e9m vivo e apaixonante por entre tantos estados! Voc\u00ea j\u00e1 ouviu falar de todos eles? Comenta quem mais deveria fazer parte dessa lista e sua m\u00fasica preferida!<\/p>\n<ul>\n<li><a href=\"https:\/\/pt.wikipedia.org\/wiki\/Luiz_Gonzaga\" target=\"_blank\" rel=\"noopener\">Luiz Gonzaga<\/a><\/li>\n<\/ul>\n<p>O\u00a0<strong>Rei do Bai\u00e3o<\/strong>\u00a0n\u00e3o tem esse nome \u00e0 toa, n\u00e3o \u00e9 mesmo?\u00a0<strong>Luiz Gonzaga do Nascimento<\/strong>\u00a0j\u00e1 tocava sanfona desde pequeno e transparecia sua origem nordestina em suas roupas, seu sotaque e a cria\u00e7\u00e3o do seu pr\u00f3prio estilo musical elevou o status da sanfona no pa\u00eds.<\/p>\n<ul>\n<li><a href=\"https:\/\/pt.wikipedia.org\/wiki\/Dominguinhos\" target=\"_blank\" rel=\"noopener\">Dominguinhos<\/a><\/li>\n<\/ul>\n<p>Desde pequeno, seguindo os passos do pai,\u00a0<strong>Jos\u00e9 Domingos de Morais<\/strong>\u00a0j\u00e1 se interessava pelo instrumento e aos seis anos come\u00e7ou a tocar sanfona. Assim ele consolidou sua carreira pr\u00f3pria com g\u00eaneros musicais como bossa nova, jazz e pop.<\/p>\n<ul>\n<li><a href=\"https:\/\/pt.wikipedia.org\/wiki\/Oswaldinho_do_Acordeon\" target=\"_blank\" rel=\"noopener\">Oswaldinho<\/a><\/li>\n<\/ul>\n<p>Nascido em Duque de Caxias,\u00a0<strong>Oswaldo de Almeida Silva<\/strong>\u00a0\u00e9 filho de Pedro Sertanejo que fez seu nome como o pioneiro dos forr\u00f3s em S\u00e3o Paulo. Oswaldinho seguiu os passos do pai e teve grande sucesso com a fus\u00e3o da 5\u00aa sinfonia de Beethoven e ritmos nordestinos.<\/p>\n<ul>\n<li><a href=\"https:\/\/pt.wikipedia.org\/wiki\/Lucy_Alves\" target=\"_blank\" rel=\"noopener\">Lucy Alves<\/a><\/li>\n<\/ul>\n<p>Nascida em 1986,\u00a0<strong>Lucy Alves Pereira<\/strong>\u00a0come\u00e7ou sua carreira com apenas 4 anos de idade. De Jo\u00e3o Pessoa ela gravou e tocou ao lado de grandes nomes como Dominguinhos, Oswaldinho e Sivuca. Ela ganhou repercuss\u00e3o nacional ao participar do\u00a0<strong>The Voice Brasil na TV Globo<\/strong>, chegando \u00e0 final e assinando um contrato com a gravadora\u00a0<strong>Universal Music<\/strong>.<\/p>\n<h2>Como aprender acordeon<\/h2>\n<p>Pode parecer complexo, mas n\u00e3o \u00e9! Na verdade, assim como a constru\u00e7\u00e3o de uma casa aprender a tocar acordeon tamb\u00e9m leva tempo e depende de etapas para ser finalizado.<\/p>\n<p>Para compreender melhor a analogia, devemos pensar na estrutura e considerar como o alicerce do acordeon, o ritmo. Ap\u00f3s o alicerce, devemos colocar as paredes que aqui \u00e9 entendido como a melodia do instrumento para s\u00f3 depois podermos colocar o telhado, ou seja, a harmonia.<\/p>\n<p>N\u00e3o devemos nos apressar quando o assunto \u00e9 aprender, por isso \u00e9 sempre importante iniciar com a base para depois podermos construir em cima!<\/p>\n<h2>Aprender a tocar acordeon online funciona?<\/h2>\n<p>Sim! Aprender um instrumento com o acordeon de forma online n\u00e3o s\u00f3 traz consigo maior comodidade, como tamb\u00e9m lhe coloca junto de outros apaixonados por acordeon em busca de manusear com maestria esse instrumento cheio de hist\u00f3ria e significado para o povo brasileiro.<\/p>\n<p>\u00c9 por isso que com a metodologia do\u00a0<strong>Rafael Vazzani<\/strong>\u00a0voc\u00ea pode se dedicar ao aprendizado com um especialista em ensino online e um verdadeiro apaixonado por acordeon!<\/p>\n<p>Venha saber mais sobre o acordeon com a gente para exercitar sua mente e seu cora\u00e7\u00e3o com este instrumento representativo da cultura brasileira!<\/p>\n<p>_<\/p>\n<p><em>Imagens gentilmente cedidas por\u00a0<a href=\"https:\/\/br.freepik.com\/home\" target=\"_blank\" rel=\"noopener\">Freepik<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com uma trajet\u00f3ria de mais de 3.000 anos ao redor do mundo, a sanfona encontrou em diversas culturas uma forma de expressas seus sons \u00fanicos e vers\u00e1teis. Pensando nisso, preparamos este artigo com a relev\u00e2ncia cultural predominantemente brasileira desse instrumento t\u00e3o amado em diversos ritmos musicais. \u00c9 um instrumento popular no mundo? Sim, apesar de[&#8230;]\n","protected":false},"author":3,"featured_media":699,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":[],"categories":[4],"tags":[238,209,224,231,240,198,235,237,88,239,229,236,234,230,228,242,227,226,206,225,232,241,157],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v18.0 (Yoast SEO v19.10) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A import\u00e2ncia cultural da sanfona! - Aula de Acordeon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A import\u00e2ncia cultural da sanfona!\" \/>\n<meta property=\"og:description\" content=\"Com uma trajet\u00f3ria de mais de 3.000 anos ao redor do mundo, a sanfona encontrou em diversas culturas uma forma de expressas seus sons \u00fanicos e vers\u00e1teis. Pensando nisso, preparamos este artigo com a relev\u00e2ncia cultural predominantemente brasileira desse instrumento t\u00e3o amado em diversos ritmos musicais. \u00c9 um instrumento popular no mundo? Sim, apesar de[...]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Aula de Acordeon\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/rafaelvanazzi\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-12T07:00:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-13T20:27:49+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/auladeacordeon.com.br\/blog\/wp-content\/uploads\/2022\/01\/aula-de-acordeon-rafa-vannazi-cultura-nacional-popular-no-mundo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rafa Vanazzi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rafa Vanazzi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/\"},\"author\":{\"name\":\"Rafa Vanazzi\",\"@id\":\"https:\/\/auladeacordeon.com.br\/blog\/#\/schema\/person\/d282872940f9be9f1beab48368d5b634\"},\"headline\":\"A import\u00e2ncia cultural da sanfona!\",\"datePublished\":\"2022-01-12T07:00:46+00:00\",\"dateModified\":\"2022-04-13T20:27:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/\"},\"wordCount\":1179,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/auladeacordeon.com.br\/blog\/#organization\"},\"keywords\":[\"afina\u00e7\u00e3o\",\"Concertina\",\"culturas\",\"fado\",\"festas juninas\",\"forr\u00f3\",\"Hermeto Pascoal\",\"instrumentistas\",\"instrumento\",\"interpreta\u00e7\u00e3o\",\"melodias\",\"Mirco Patarini\",\"m\u00fasica erudita\",\"m\u00fasica folcl\u00f3rica\",\"m\u00fasica nordestina\",\"pisadinha\",\"popular\",\"ritmos musicais\",\"Sanfona\",\"sons\",\"tango\",\"tecnobrega\",\"valsas\"],\"articleSection\":[\"Artigos\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/\",\"url\":\"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/\",\"name\":\"A import\u00e2ncia cultural da sanfona! - Aula de Acordeon\",\"isPartOf\":{\"@id\":\"https:\/\/auladeacordeon.com.br\/blog\/#website\"},\"datePublished\":\"2022-01-12T07:00:46+00:00\",\"dateModified\":\"2022-04-13T20:27:49+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/auladeacordeon.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A import\u00e2ncia cultural da sanfona!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/auladeacordeon.com.br\/blog\/#website\",\"url\":\"https:\/\/auladeacordeon.com.br\/blog\/\",\"name\":\"Aula de Acordeon\",\"description\":\"Blog\",\"publisher\":{\"@id\":\"https:\/\/auladeacordeon.com.br\/blog\/#organization\"},\"alternateName\":\"Artigos e textos para quem ama acordeon\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/auladeacordeon.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/auladeacordeon.com.br\/blog\/#organization\",\"name\":\"Aula de Acordeon\",\"url\":\"https:\/\/auladeacordeon.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/auladeacordeon.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/auladeacordeon.com.br\/blog\/wp-content\/uploads\/2022\/11\/logo_apaixonados_fundo_branco_v1-scaled.jpg\",\"contentUrl\":\"https:\/\/auladeacordeon.com.br\/blog\/wp-content\/uploads\/2022\/11\/logo_apaixonados_fundo_branco_v1-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Aula de Acordeon\"},\"image\":{\"@id\":\"https:\/\/auladeacordeon.com.br\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/auladeacordeon.com.br\/blog\/#\/schema\/person\/d282872940f9be9f1beab48368d5b634\",\"name\":\"Rafa Vanazzi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/auladeacordeon.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f7b66a4dcfa10cbbc1315a89a8740e02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f7b66a4dcfa10cbbc1315a89a8740e02?s=96&d=mm&r=g\",\"caption\":\"Rafa Vanazzi\"},\"description\":\"M\u00fasico com mestrado em Musicografia Braille na UNICAMP, Rafael \u00e9 professor de m\u00fasica com especialidade em acordeon.\",\"sameAs\":[\"https:\/\/www.apaixonadosporacordeon.com.br\/\",\"https:\/\/www.facebook.com\/rafaelvanazzi\",\"https:\/\/www.instagram.com\/apaixonadosporacordeon\/\",\"https:\/\/www.youtube.com\/rafavanazzi\"],\"url\":\"https:\/\/auladeacordeon.com.br\/blog\/author\/rafa\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"A import\u00e2ncia cultural da sanfona! - Aula de Acordeon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/","og_locale":"pt_BR","og_type":"article","og_title":"A import\u00e2ncia cultural da sanfona!","og_description":"Com uma trajet\u00f3ria de mais de 3.000 anos ao redor do mundo, a sanfona encontrou em diversas culturas uma forma de expressas seus sons \u00fanicos e vers\u00e1teis. Pensando nisso, preparamos este artigo com a relev\u00e2ncia cultural predominantemente brasileira desse instrumento t\u00e3o amado em diversos ritmos musicais. \u00c9 um instrumento popular no mundo? Sim, apesar de[...]","og_url":"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/","og_site_name":"Aula de Acordeon","article_author":"https:\/\/www.facebook.com\/rafaelvanazzi","article_published_time":"2022-01-12T07:00:46+00:00","article_modified_time":"2022-04-13T20:27:49+00:00","og_image":[{"width":1280,"height":720,"url":"http:\/\/auladeacordeon.com.br\/blog\/wp-content\/uploads\/2022\/01\/aula-de-acordeon-rafa-vannazi-cultura-nacional-popular-no-mundo.jpg","type":"image\/jpeg"}],"author":"Rafa Vanazzi","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rafa Vanazzi","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/#article","isPartOf":{"@id":"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/"},"author":{"name":"Rafa Vanazzi","@id":"https:\/\/auladeacordeon.com.br\/blog\/#\/schema\/person\/d282872940f9be9f1beab48368d5b634"},"headline":"A import\u00e2ncia cultural da sanfona!","datePublished":"2022-01-12T07:00:46+00:00","dateModified":"2022-04-13T20:27:49+00:00","mainEntityOfPage":{"@id":"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/"},"wordCount":1179,"commentCount":0,"publisher":{"@id":"https:\/\/auladeacordeon.com.br\/blog\/#organization"},"keywords":["afina\u00e7\u00e3o","Concertina","culturas","fado","festas juninas","forr\u00f3","Hermeto Pascoal","instrumentistas","instrumento","interpreta\u00e7\u00e3o","melodias","Mirco Patarini","m\u00fasica erudita","m\u00fasica folcl\u00f3rica","m\u00fasica nordestina","pisadinha","popular","ritmos musicais","Sanfona","sons","tango","tecnobrega","valsas"],"articleSection":["Artigos"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/","url":"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/","name":"A import\u00e2ncia cultural da sanfona! - Aula de Acordeon","isPartOf":{"@id":"https:\/\/auladeacordeon.com.br\/blog\/#website"},"datePublished":"2022-01-12T07:00:46+00:00","dateModified":"2022-04-13T20:27:49+00:00","breadcrumb":{"@id":"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/auladeacordeon.com.br\/blog\/a-importancia-cultural-da-sanfona-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/auladeacordeon.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"A import\u00e2ncia cultural da sanfona!"}]},{"@type":"WebSite","@id":"https:\/\/auladeacordeon.com.br\/blog\/#website","url":"https:\/\/auladeacordeon.com.br\/blog\/","name":"Aula de Acordeon","description":"Blog","publisher":{"@id":"https:\/\/auladeacordeon.com.br\/blog\/#organization"},"alternateName":"Artigos e textos para quem ama acordeon","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auladeacordeon.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/auladeacordeon.com.br\/blog\/#organization","name":"Aula de Acordeon","url":"https:\/\/auladeacordeon.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/auladeacordeon.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/auladeacordeon.com.br\/blog\/wp-content\/uploads\/2022\/11\/logo_apaixonados_fundo_branco_v1-scaled.jpg","contentUrl":"https:\/\/auladeacordeon.com.br\/blog\/wp-content\/uploads\/2022\/11\/logo_apaixonados_fundo_branco_v1-scaled.jpg","width":2560,"height":2560,"caption":"Aula de Acordeon"},"image":{"@id":"https:\/\/auladeacordeon.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/auladeacordeon.com.br\/blog\/#\/schema\/person\/d282872940f9be9f1beab48368d5b634","name":"Rafa Vanazzi","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/auladeacordeon.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f7b66a4dcfa10cbbc1315a89a8740e02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f7b66a4dcfa10cbbc1315a89a8740e02?s=96&d=mm&r=g","caption":"Rafa Vanazzi"},"description":"M\u00fasico com mestrado em Musicografia Braille na UNICAMP, Rafael \u00e9 professor de m\u00fasica com especialidade em acordeon.","sameAs":["https:\/\/www.apaixonadosporacordeon.com.br\/","https:\/\/www.facebook.com\/rafaelvanazzi","https:\/\/www.instagram.com\/apaixonadosporacordeon\/","https:\/\/www.youtube.com\/rafavanazzi"],"url":"https:\/\/auladeacordeon.com.br\/blog\/author\/rafa\/"}]}},"_links":{"self":[{"href":"https:\/\/auladeacordeon.com.br\/blog\/wp-json\/wp\/v2\/posts\/780"}],"collection":[{"href":"https:\/\/auladeacordeon.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/auladeacordeon.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/auladeacordeon.com.br\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/auladeacordeon.com.br\/blog\/wp-json\/wp\/v2\/comments?post=780"}],"version-history":[{"count":0,"href":"https:\/\/auladeacordeon.com.br\/blog\/wp-json\/wp\/v2\/posts\/780\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auladeacordeon.com.br\/blog\/wp-json\/wp\/v2\/media\/699"}],"wp:attachment":[{"href":"https:\/\/auladeacordeon.com.br\/blog\/wp-json\/wp\/v2\/media?parent=780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/auladeacordeon.com.br\/blog\/wp-json\/wp\/v2\/categories?post=780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/auladeacordeon.com.br\/blog\/wp-json\/wp\/v2\/tags?post=780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}